{"id":3787,"date":"2025-07-30T14:29:18","date_gmt":"2025-07-30T12:29:18","guid":{"rendered":"https:\/\/roosplan.de\/?p=3787"},"modified":"2025-07-30T14:29:20","modified_gmt":"2025-07-30T12:29:20","slug":"ausgleichsflaeche-fuer-zauneidechsen","status":"publish","type":"post","link":"https:\/\/roosplan.de\/en\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/","title":{"rendered":"\u00a0Ausgleichsfl\u00e4che f\u00fcr Zauneidechsen"},"content":{"rendered":"<div id=\"new-royalslider-55\" class=\"royalSlider new-royalslider-55 rsDefaultInv visibleNearbyZoom\" style=\"width:100%;height:600px;;\" data-rs-options='{&quot;template&quot;:&quot;default&quot;,&quot;image_generation&quot;:{&quot;imageWidth&quot;:&quot;&quot;,&quot;imageHeight&quot;:&quot;&quot;,&quot;thumbImageWidth&quot;:&quot;&quot;,&quot;thumbImageHeight&quot;:&quot;&quot;},&quot;thumbs&quot;:{&quot;thumbWidth&quot;:96,&quot;thumbHeight&quot;:72},&quot;autoPlay&quot;:{&quot;enabled&quot;:&quot;true&quot;},&quot;visibleNearby&quot;:{&quot;enabled&quot;:&quot;true&quot;,&quot;centerArea&quot;:0.80000000000000004,&quot;breakpoint&quot;:650,&quot;breakpointCenterArea&quot;:0.64000000000000001,&quot;navigateByCenterClick&quot;:&quot;true&quot;},&quot;video&quot;:{&quot;autoHideBlocks&quot;:&quot;true&quot;},&quot;block&quot;:{&quot;moveOffset&quot;:20,&quot;speed&quot;:400,&quot;delay&quot;:200},&quot;width&quot;:&quot;100%&quot;,&quot;height&quot;:600,&quot;autoScaleSliderWidth&quot;:1024,&quot;autoScaleSliderHeight&quot;:640,&quot;imageScaleMode&quot;:&quot;fit&quot;,&quot;imageScalePadding&quot;:1,&quot;controlNavigation&quot;:&quot;none&quot;,&quot;loop&quot;:&quot;true&quot;,&quot;keyboardNavEnabled&quot;:&quot;true&quot;,&quot;addActiveClass&quot;:&quot;true&quot;}'>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/roosplan.de\/wp-content\/uploads\/2025\/06\/250604_AusgleichsflaecheZauneidechsen_01-1024x682.jpg\" alt=\"250604_AusgleichsflaecheZauneidechsen_01\"\/>\n  \n  <div class=\"rsCaption\">\n    <h5>250604_AusgleichsflaecheZauneidechsen_01<\/h5>\n    <span><\/span>\n  <\/div>\n  \n  \n<\/div>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/roosplan.de\/wp-content\/uploads\/2025\/06\/250604_AusgleichsflaecheZauneidechsen_02-1024x682.jpg\" alt=\"250604_AusgleichsflaecheZauneidechsen_02\"\/>\n  \n  <div class=\"rsCaption\">\n    <h5>250604_AusgleichsflaecheZauneidechsen_02<\/h5>\n    <span><\/span>\n  <\/div>\n  \n  \n<\/div>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/roosplan.de\/wp-content\/uploads\/2025\/06\/250604_AusgleichsflaecheZauneidechsen_03-682x1024.jpg\" alt=\"250604_AusgleichsflaecheZauneidechsen_03\"\/>\n  \n  <div class=\"rsCaption\">\n    <h5>250604_AusgleichsflaecheZauneidechsen_03<\/h5>\n    <span><\/span>\n  <\/div>\n  \n  \n<\/div>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/roosplan.de\/wp-content\/uploads\/2025\/06\/250604_AusgleichsflaecheZauneidechsen_04-682x1024.jpg\" alt=\"250604_AusgleichsflaecheZauneidechsen_04\"\/>\n  \n  <div class=\"rsCaption\">\n    <h5>250604_AusgleichsflaecheZauneidechsen_04<\/h5>\n    <span><\/span>\n  <\/div>\n  \n  \n<\/div>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/roosplan.de\/wp-content\/uploads\/2025\/06\/250604_AusgleichsflaecheZauneidechsen_05-682x1024.jpg\" alt=\"250604_AusgleichsflaecheZauneidechsen_05\"\/>\n  \n  <div class=\"rsCaption\">\n    <h5>250604_AusgleichsflaecheZauneidechsen_05<\/h5>\n    <span><\/span>\n  <\/div>\n  \n  \n<\/div>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/roosplan.de\/wp-content\/uploads\/2025\/06\/250604_AusgleichsflaecheZauneidechsen_06-1024x682.jpg\" alt=\"250604_AusgleichsflaecheZauneidechsen_06\"\/>\n  \n  <div class=\"rsCaption\">\n    <h5>250604_AusgleichsflaecheZauneidechsen_06<\/h5>\n    <span><\/span>\n  <\/div>\n  \n  \n<\/div>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/roosplan.de\/wp-content\/uploads\/2025\/06\/250604_AusgleichsflaecheZauneidechsen_07-1024x682.jpg\" alt=\"250604_AusgleichsflaecheZauneidechsen_07\"\/>\n  \n  <div class=\"rsCaption\">\n    <h5>250604_AusgleichsflaecheZauneidechsen_07<\/h5>\n    <span><\/span>\n  <\/div>\n  \n  \n<\/div>\n<div class=\"rsContent\">\n  <img decoding=\"async\" class=\"rsImg\" src=\"https:\/\/roosplan.de\/wp-content\/uploads\/2025\/06\/250604_AusgleichsflaecheZauneidechsen_08-1024x682.jpg\" alt=\"250604_AusgleichsflaecheZauneidechsen_08\"\/>\n  \n  <div class=\"rsCaption\">\n    <h5>250604_AusgleichsflaecheZauneidechsen_08<\/h5>\n    <span><\/span>\n  <\/div>\n  \n  \n<\/div>\n\n<\/div>\n\n\n<h2 class=\"wp-block-post-title\">\u00a0Ausgleichsfl\u00e4che f\u00fcr Zauneidechsen<\/h2>\n\n\n<p><strong>Client<\/strong> <br>Weissach im Tal<\/p>\n\n\n\n<p><strong>Beschreibung:<\/strong><br>Im Rahmen eines erforderlichen R\u00fcckbaus von Auff\u00fcllungen und der Genehmigung eines Kompost- und Erdzwischenlagers,&nbsp;musste eine im Gebiet vorkommende Population der streng gesch\u00fctzten Zauneidechse in direkt angrenzende Ausgleichsfl\u00e4chen umgesetzt werden. Unser B\u00fcro hat alle Aufgaben, von der Kartierung der Ausgangspopulation \u00fcber die Planung der Ausgleichsfl\u00e4chen bis zum&nbsp;Abfang und Umsetzung der Eidechsen und dem Monitoring , \u00fcbernommen. Dabei erfolgte stets eine enge Abstimmung zwischen der Gemeinde, den Beh\u00f6rden und dem ausf\u00fchrenden Bauhof.<\/p>\n\n\n\n<p><strong>Ausf\u00fchrungszeitraum:<br><\/strong>2017 \u2013 heute<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"javascript: history.go(-1)\">Zur\u00fcck<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Artenschutzrechtliche Begleitung der baulichen Eingriffe in zwei Bodenmieten<\/p>","protected":false},"author":8,"featured_media":3792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"default","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"[\"content\",\"tags\"]","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"_links_to":"","_links_to_target":""},"categories":[53],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00a0Ausgleichsfl\u00e4che f\u00fcr Zauneidechsen - roosplan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/roosplan.de\/en\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a0Ausgleichsfl\u00e4che f\u00fcr Zauneidechsen - roosplan\" \/>\n<meta property=\"og:description\" content=\"Artenschutzrechtliche Begleitung der baulichen Eingriffe in zwei Bodenmieten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/roosplan.de\/en\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/\" \/>\n<meta property=\"og:site_name\" content=\"roosplan\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T12:29:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T12:29:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/roosplan.de\/wp-content\/uploads\/2025\/06\/250604_AusgleichsflaecheZauneidechsen_04.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1333\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Natalie Klenk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalie Klenk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/\"},\"author\":{\"name\":\"Natalie Klenk\",\"@id\":\"https:\/\/roosplan.de\/#\/schema\/person\/f98b480305056921ae70f0493ecc9c9f\"},\"headline\":\"\u00a0Ausgleichsfl\u00e4che f\u00fcr Zauneidechsen\",\"datePublished\":\"2025-07-30T12:29:18+00:00\",\"dateModified\":\"2025-07-30T12:29:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/\"},\"wordCount\":96,\"publisher\":{\"@id\":\"https:\/\/roosplan.de\/#organization\"},\"articleSection\":[\"Artenschutz\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/\",\"url\":\"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/\",\"name\":\"\u00a0Ausgleichsfl\u00e4che f\u00fcr Zauneidechsen - roosplan\",\"isPartOf\":{\"@id\":\"https:\/\/roosplan.de\/#website\"},\"datePublished\":\"2025-07-30T12:29:18+00:00\",\"dateModified\":\"2025-07-30T12:29:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/roosplan.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a0Ausgleichsfl\u00e4che f\u00fcr Zauneidechsen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/roosplan.de\/#website\",\"url\":\"https:\/\/roosplan.de\/\",\"name\":\"roosplan\",\"description\":\"Planungsb\u00fcro f\u00fcr Freiraum, Stadt und Landschaft\",\"publisher\":{\"@id\":\"https:\/\/roosplan.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/roosplan.de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/roosplan.de\/#organization\",\"name\":\"roosplan\",\"url\":\"https:\/\/roosplan.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/roosplan.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/roosplan.de\/wp-content\/uploads\/2022\/05\/cropped-roosplan-logo-web.jpg\",\"contentUrl\":\"https:\/\/roosplan.de\/wp-content\/uploads\/2022\/05\/cropped-roosplan-logo-web.jpg\",\"width\":583,\"height\":138,\"caption\":\"roosplan\"},\"image\":{\"@id\":\"https:\/\/roosplan.de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/roosplan.de\/#\/schema\/person\/f98b480305056921ae70f0493ecc9c9f\",\"name\":\"Natalie Klenk\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a0Ausgleichsfl\u00e4che f\u00fcr Zauneidechsen - roosplan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/roosplan.de\/en\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/","og_locale":"en_GB","og_type":"article","og_title":"\u00a0Ausgleichsfl\u00e4che f\u00fcr Zauneidechsen - roosplan","og_description":"Artenschutzrechtliche Begleitung der baulichen Eingriffe in zwei Bodenmieten","og_url":"https:\/\/roosplan.de\/en\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/","og_site_name":"roosplan","article_published_time":"2025-07-30T12:29:18+00:00","article_modified_time":"2025-07-30T12:29:20+00:00","og_image":[{"width":1333,"height":2000,"url":"https:\/\/roosplan.de\/wp-content\/uploads\/2025\/06\/250604_AusgleichsflaecheZauneidechsen_04.jpg","type":"image\/jpeg"}],"author":"Natalie Klenk","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Natalie Klenk","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/#article","isPartOf":{"@id":"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/"},"author":{"name":"Natalie Klenk","@id":"https:\/\/roosplan.de\/#\/schema\/person\/f98b480305056921ae70f0493ecc9c9f"},"headline":"\u00a0Ausgleichsfl\u00e4che f\u00fcr Zauneidechsen","datePublished":"2025-07-30T12:29:18+00:00","dateModified":"2025-07-30T12:29:20+00:00","mainEntityOfPage":{"@id":"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/"},"wordCount":96,"publisher":{"@id":"https:\/\/roosplan.de\/#organization"},"articleSection":["Artenschutz"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/","url":"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/","name":"\u00a0Ausgleichsfl\u00e4che f\u00fcr Zauneidechsen - roosplan","isPartOf":{"@id":"https:\/\/roosplan.de\/#website"},"datePublished":"2025-07-30T12:29:18+00:00","dateModified":"2025-07-30T12:29:20+00:00","breadcrumb":{"@id":"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/roosplan.de\/artenschutz\/ausgleichsflaeche-fuer-zauneidechsen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/roosplan.de\/"},{"@type":"ListItem","position":2,"name":"\u00a0Ausgleichsfl\u00e4che f\u00fcr Zauneidechsen"}]},{"@type":"WebSite","@id":"https:\/\/roosplan.de\/#website","url":"https:\/\/roosplan.de\/","name":"roosplan","description":"Planungsb\u00fcro f\u00fcr Freiraum, Stadt und Landschaft","publisher":{"@id":"https:\/\/roosplan.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/roosplan.de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/roosplan.de\/#organization","name":"roosplan","url":"https:\/\/roosplan.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/roosplan.de\/#\/schema\/logo\/image\/","url":"https:\/\/roosplan.de\/wp-content\/uploads\/2022\/05\/cropped-roosplan-logo-web.jpg","contentUrl":"https:\/\/roosplan.de\/wp-content\/uploads\/2022\/05\/cropped-roosplan-logo-web.jpg","width":583,"height":138,"caption":"roosplan"},"image":{"@id":"https:\/\/roosplan.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/roosplan.de\/#\/schema\/person\/f98b480305056921ae70f0493ecc9c9f","name":"Natalie Klenk"}]}},"_links":{"self":[{"href":"https:\/\/roosplan.de\/en\/wp-json\/wp\/v2\/posts\/3787"}],"collection":[{"href":"https:\/\/roosplan.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roosplan.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roosplan.de\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/roosplan.de\/en\/wp-json\/wp\/v2\/comments?post=3787"}],"version-history":[{"count":5,"href":"https:\/\/roosplan.de\/en\/wp-json\/wp\/v2\/posts\/3787\/revisions"}],"predecessor-version":[{"id":3952,"href":"https:\/\/roosplan.de\/en\/wp-json\/wp\/v2\/posts\/3787\/revisions\/3952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roosplan.de\/en\/wp-json\/wp\/v2\/media\/3792"}],"wp:attachment":[{"href":"https:\/\/roosplan.de\/en\/wp-json\/wp\/v2\/media?parent=3787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roosplan.de\/en\/wp-json\/wp\/v2\/categories?post=3787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roosplan.de\/en\/wp-json\/wp\/v2\/tags?post=3787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}